{"id":997,"date":"2023-03-09T08:48:05","date_gmt":"2023-03-09T07:48:05","guid":{"rendered":"https:\/\/www.boatlakexperience.it\/der-comer-see\/"},"modified":"2023-03-24T21:15:56","modified_gmt":"2023-03-24T20:15:56","slug":"der-comer-see","status":"publish","type":"page","link":"https:\/\/www.boatlakexperience.it\/de\/der-comer-see\/","title":{"rendered":"Der Comer See"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"997\" class=\"elementor elementor-997 elementor-32\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f4e182 false false elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f4e182\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-338b75c\" data-id=\"338b75c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a75fd79 elementor-widget elementor-widget-heading\" data-id=\"a75fd79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">DER COMER SEE\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52bfb49 elementor-widget elementor-widget-text-editor\" data-id=\"52bfb49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Eine Bootsfahrt am Comer See ist eine besonders sch\u00f6ne Aktivit\u00e4t. Sie bekommen die M\u00f6glichkeit, die Landschaft aus einem privilegierten Blickwinkel zu bewundern.<\/p>\n<p>Ein einzigartiges Erlebnis, um die Sch\u00f6nheiten des Sees kennenzulernen, vom ersten Becken, das von der Stadt Como \u00fcberragt wird, bis zum n\u00f6rdlichen Ende und dem Arm von Lecco.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fa0ee6 elementor-widget elementor-widget-image\" data-id=\"5fa0ee6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"899\" src=\"https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience.jpg\" class=\"attachment-full size-full wp-image-133\" alt=\"\" srcset=\"https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience.jpg 1600w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience-300x169.jpg 300w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience-1024x575.jpg 1024w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience-768x432.jpg 768w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Boat-Lake-Experience-1536x863.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8ad30d elementor-widget elementor-widget-text-editor\" data-id=\"e8ad30d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><em>&#8220;Es besteht kein Zweifel, dass dies die berauschendste Landschaft ist, die ich bisher gesehen habe. Neulich war die Landschaft au\u00dfergew\u00f6hnlich und malerisch.<\/em><br \/><em>Am gegen\u00fcberliegenden Ufer spiegelten sich die Klippen und B\u00e4ume im See<\/em><br \/><em>mit wunderbarer Klarheit und aus vielen fernen Fenstern erstreckten sich Lichtstrahlen \u00fcber die stillen Wasser.\u201c<\/em><br \/>Mark Twain, die Unschuldigen im Ausland, 1869.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9714e2f elementor-widget elementor-widget-text-editor\" data-id=\"9714e2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Der Comer See ist weltber\u00fchmt f\u00fcr seine luxuri\u00f6sen Villen und wundersch\u00f6nen G\u00e4rten. <br \/>Die neoklassizistische Villa Carlotta in Tremezzo bietet den Besuchern im Fr\u00fchling ein Meer aus Rhododendren und Azaleen. In der Villa Serbelloni in Bellagio, der Perle des Sees, ist die Geschichte sowie die Kultur der Vergangenheit noch immer stark zu sp\u00fcren: So hielten sich bekannte Pers\u00f6nlichkeiten wie Leonardo da Vinci, der Dichter Giuseppe Parini und K\u00f6nigin Victoria in dieser Villa auf. Ganz oben auf der Bucket-List stehen die G\u00e4rten der Villa Melzi.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc523c3 elementor-widget elementor-widget-text-editor\" data-id=\"cc523c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Die Villa Balbianello auf dem Lenno-Vorgebirge mit ihrem Garten und ihrer Loggia ist Eigentum des FAI, von der aus Sie ein atemberaubendes Schauspiel genie\u00dfen k\u00f6nnen. Vor Ossuccio befindet sich die einzige Insel des Lario, die Insel Comacina, mit ihren authentischen Traditionen und den Aromen aus einem anderen Zeitalter, die romanische Kirche Santa Maria Maddalena mit einem gotischen Glockenturm und den vielen K\u00fcnstlerh\u00e4usern in rationalistischen Stil. Lassen Sie sich nicht den Sacro Monte di Ossuccio entgehen, der von der UNESCO in die Liste des Weltkulturerbes aufgenommen wurde.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e563b54 elementor-widget elementor-widget-image\" data-id=\"e563b54\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"899\" src=\"https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience.jpg\" class=\"attachment-full size-full wp-image-134\" alt=\"\" srcset=\"https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience.jpg 1600w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience-300x169.jpg 300w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience-1024x575.jpg 1024w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience-768x432.jpg 768w, https:\/\/www.boatlakexperience.it\/wp-content\/uploads\/2023\/03\/Villa-Balbianello-Lenno-Boat-Lake-Experience-1536x863.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25dd23b elementor-widget elementor-widget-text-editor\" data-id=\"25dd23b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><em>&#8220;Jener Arm des Comer Sees, der sich gegen Mittag wendet, zwischen zwei ununterbrochenen Bergketten, alle in den Br\u00fcsten und in den Golfen, je nach dem Vorspringen und Zur\u00fcckkehren derselben, schrumpft fast pl\u00f6tzlich und nimmt dazwischen Lauf und Form eines Flusses an ein Vorgebirge auf der rechten Seite und eine breite K\u00fcstenlinie auf der anderen Seite; und die Br\u00fccke, die die beiden Ufer dort verbindet, scheint diese Verwandlung f\u00fcr das Auge noch empfindlicher zu machen, und markiert den Punkt, wo der See aufh\u00f6rt und die Adda wieder beginnt, um dann wieder den Namen des Sees anzunehmen, wo die Ufer, wenn man sich wieder zur\u00fcckzieht, entspannt sich das Wasser und gleitet langsam in neue Abgr\u00fcnde und neue Busen.&#8221;<\/em><br \/>Alessandro Manzoni, Die Verlobten, 1825.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DER COMER SEE Eine Bootsfahrt am Comer See ist eine besonders sch\u00f6ne Aktivit\u00e4t. Sie bekommen die M\u00f6glichkeit, die Landschaft aus einem privilegierten Blickwinkel zu bewundern. Ein einzigartiges Erlebnis, um die Sch\u00f6nheiten des Sees kennenzulernen, vom ersten Becken, das von der Stadt Como \u00fcberragt wird, bis zum n\u00f6rdlichen Ende und dem Arm von Lecco. &#8220;Es besteht [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-997","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/pages\/997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/comments?post=997"}],"version-history":[{"count":3,"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/pages\/997\/revisions"}],"predecessor-version":[{"id":1000,"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/pages\/997\/revisions\/1000"}],"wp:attachment":[{"href":"https:\/\/www.boatlakexperience.it\/de\/wp-json\/wp\/v2\/media?parent=997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}